{"id":174,"date":"2025-02-12T18:54:23","date_gmt":"2025-02-12T18:54:23","guid":{"rendered":"https:\/\/ggintegralsolutions.com\/?page_id=174"},"modified":"2026-01-27T15:41:03","modified_gmt":"2026-01-27T15:41:03","slug":"servicios","status":"publish","type":"page","link":"https:\/\/ggintegralsolutions.com\/en\/servicios\/","title":{"rendered":"Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"174\" class=\"elementor elementor-174\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33ba4a3 e-flex e-con-boxed e-con e-parent\" data-id=\"33ba4a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2982075 elementor-widget elementor-widget-heading\" data-id=\"2982075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SERVICIOS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ce8780 e-flex e-con-boxed e-con e-parent\" data-id=\"8ce8780\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c7f974 e-con-full e-flex e-con e-child\" data-id=\"9c7f974\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a513c0d elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7a513c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 1  <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fd7580f elementor-widget elementor-widget-elementskit-heading\" data-id=\"5fd7580f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">IMPUESTOS PERSONALES<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Nos aseguramos de que declares tus impuestos de manera correcta, maximizando<br \/>deducciones y cr\u00e9ditos fiscales que pueden reducir tu carga tributaria. Te ayudamos con:<br \/>\u2714\ufe0f Declaraci\u00f3n de impuestos individuales (Formulario 1040)<br \/>\u2714\ufe0f Cr\u00e9ditos fiscales como el Earned Income Tax Credit (EITC) y el Child Tax Credit (CTC)<br \/>\u2714\ufe0f Planificaci\u00f3n fiscal para aut\u00f3nomos y freelancers (Schedule C)<br \/>\u2714\ufe0f Declaraciones de impuestos para extranjeros con ITIN<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8b675c elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"f8b675c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tCotiza aqu\u00ed sin costo\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae436e9 e-con-full e-flex e-con e-child\" data-id=\"ae436e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00374b3 elementor-widget elementor-widget-image\" data-id=\"00374b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-PERSONALES-TAXES-PERSONALES-1024x640.png\" class=\"attachment-large size-large wp-image-348\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-PERSONALES-TAXES-PERSONALES-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-PERSONALES-TAXES-PERSONALES-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-PERSONALES-TAXES-PERSONALES-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-PERSONALES-TAXES-PERSONALES-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-PERSONALES-TAXES-PERSONALES.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a38653 e-flex e-con-boxed e-con e-parent\" data-id=\"0a38653\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bd56c7d e-con-full e-flex e-con e-child\" data-id=\"bd56c7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-045ac93 elementor-widget elementor-widget-image\" data-id=\"045ac93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/ITIN-1024x640.png\" class=\"attachment-large size-large wp-image-349\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/ITIN-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/ITIN-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/ITIN-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/ITIN-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/ITIN.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dd36b9 e-con-full e-flex e-con e-child\" data-id=\"2dd36b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7507b0a elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7507b0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 2 <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e3605 elementor-widget elementor-widget-elementskit-heading\" data-id=\"74e3605\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">ITIN<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Asistimos en la obtenci\u00f3n del ITIN, un n\u00famero de identificaci\u00f3n fiscal para individuos que requieren cumplir con obligaciones tributarias en los Estados Unidos pero no son elegibles para un N\u00famero de Seguro Social. Nuestro proceso garantiza la seguridad de tus documentos, evitando el env\u00edo f\u00edsico de tu pasaporte.<\/p>\n<p>No pagues m\u00e1s de lo necesario. Con una estrategia fiscal efectiva, podemos ayudarte obtener el mayor reembolso posible y a cumplir con todas las regulaciones del IRS.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2210824 elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"2210824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tEscribenos\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30052c0 e-flex e-con-boxed e-con e-parent\" data-id=\"30052c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-256b648 e-con-full e-flex e-con e-child\" data-id=\"256b648\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03e3082 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"03e3082\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 3 <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09e2d25 elementor-widget elementor-widget-elementskit-heading\" data-id=\"09e2d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">IMPUESTOS CORPORATIVOS<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>(TAXES PARA EMPRESAS)<\/p>\n<p>Ayudamos a empresarios y due\u00f1os de negocios a presentar correctamente sus impuestos y reducir la carga fiscal con una planificaci\u00f3n estrat\u00e9gica. Trabajamos con:<br \/>\u2714\ufe0f Impuestos para LLC, S-Corp y C-Corp<br \/>\u2714\ufe0f Presentaci\u00f3n de formularios 1120 (Corporaciones) y 1065 (Sociedades)<br \/>\u2714\ufe0f Deducciones y estrategias para reducir la carga tributaria<br \/>\u2714\ufe0f Cumplimiento de impuestos estatales y locales.<br \/>\u2714\ufe0f Gestionamos la presentaci\u00f3n del Reporte BOI<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6af5bec elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"6af5bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tContacto\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9fea55 e-con-full e-flex e-con e-child\" data-id=\"c9fea55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e310f9 elementor-widget elementor-widget-image\" data-id=\"6e310f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-CORPORATIVOS-1024x640.png\" class=\"attachment-large size-large wp-image-350\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-CORPORATIVOS-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-CORPORATIVOS-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-CORPORATIVOS-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-CORPORATIVOS-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/IMPUESTOS-CORPORATIVOS.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-922eb12 e-flex e-con-boxed e-con e-parent\" data-id=\"922eb12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7412915 e-con-full e-flex e-con e-child\" data-id=\"7412915\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8b50a3 elementor-widget elementor-widget-image\" data-id=\"f8b50a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/registro-de-empresa-1024x640.png\" class=\"attachment-large size-large wp-image-351\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/registro-de-empresa-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/registro-de-empresa-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/registro-de-empresa-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/registro-de-empresa-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/registro-de-empresa.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-508075b e-con-full e-flex e-con e-child\" data-id=\"508075b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0a8b63 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"b0a8b63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 4<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa86bc3 elementor-widget elementor-widget-elementskit-heading\" data-id=\"fa86bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">Registro de Empresas y Contabilidad<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Asistimos en el proceso de formaci\u00f3n y registro de entidades legales como LLC (Limited Liability Company), S-Corp (S Corporation) y C Corp (C Corporation), asegurando que cumplas con los requisitos fiscales y legales tanto a nivel estatal como federal. Adem\u00e1s, ofrecemos servicios de contabilidad continua para garantizar que tu negocio mantenga registros financieros precisos y cumpla con todas sus obligaciones tributarias.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baf4a1e elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"baf4a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tCotiza sin compromiso\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fed0a8 e-flex e-con-boxed e-con e-parent\" data-id=\"7fed0a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4be8e7a e-con-full e-flex e-con e-child\" data-id=\"4be8e7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ac2831 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"8ac2831\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 5<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f766d86 elementor-widget elementor-widget-elementskit-heading\" data-id=\"f766d86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">ASESOR\u00cdA FINANCIERA INTEGRAL Y PLANES DE RETIRO<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>M\u00e1s all\u00e1 de los seguros de vida y salud, ofrecemos una asesor\u00eda financiera personalizada para ayudarte a alcanzar tus metas econ\u00f3micas y asegurar tu futuro.<br \/>Nuestros servicios incluyen:<br \/><strong>Estrategias de Jubilaci\u00f3n:<\/strong> Dise\u00f1amos planes de retiro adaptados a tus necesidades, asegurando que disfrutes de una jubilaci\u00f3n c\u00f3moda y sin preocupaciones financieras.<br \/><strong>Planificaci\u00f3n Educativa:<\/strong> Te ayudamos a preparar financieramente la educaci\u00f3n de tus hijos, creando fondos que garanticen su formaci\u00f3n acad\u00e9mica.<br \/><strong>Preservaci\u00f3n Patrimonial:<\/strong> Implementamos estrategias para proteger y maximizar tu patrimonio, asegurando su transferencia eficiente a las futuras generaciones.<br \/><strong>Soluciones Empresariales:<\/strong> Asesoramos a propietarios de negocios en la<br \/>implementaci\u00f3n de planes financieros que fortalezcan y protejan sus empresas.<\/p>\n<p>Nuestros profesionales financieros est\u00e1n comprometidos en educarte y guiarte en cada paso, creando estrategias personalizadas que se alineen con tus objetivos y circunstancias espec\u00edficas. Con nuestro apoyo, podr\u00e1s tomar decisiones informadas y construir un futuro financiero s\u00f3lido para ti y tus seres queridos.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-218e0cb elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"218e0cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tCotiza aqu\u00ed sin costo\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-774de14 e-con-full e-flex e-con e-child\" data-id=\"774de14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0491eca elementor-widget elementor-widget-image\" data-id=\"0491eca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/planes-de-retiro-1024x640.png\" class=\"attachment-large size-large wp-image-354\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/planes-de-retiro-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/planes-de-retiro-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/planes-de-retiro-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/planes-de-retiro-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/planes-de-retiro.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1927710 e-flex e-con-boxed e-con e-parent\" data-id=\"1927710\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bc8bda1 e-con-full e-flex e-con e-child\" data-id=\"bc8bda1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b79a79 elementor-widget elementor-widget-image\" data-id=\"6b79a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/impuestos-internacionales-1024x640.png\" class=\"attachment-large size-large wp-image-353\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/impuestos-internacionales-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/impuestos-internacionales-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/impuestos-internacionales-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/impuestos-internacionales-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/impuestos-internacionales.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50d1e10 e-con-full e-flex e-con e-child\" data-id=\"50d1e10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70769a9 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"70769a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 6<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa133bb elementor-widget elementor-widget-elementskit-heading\" data-id=\"fa133bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">IMPUESTOS INTERNACIONALES<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><strong> Y ASESOR\u00cdA PARA EMPRENDEDORES<\/strong><\/p>\n<p>Si eres extranjero y deseas abrir una empresa en EE.UU., te ayudamos a estructurar tu negocio de forma que evites la doble tributaci\u00f3n y maximices tus beneficios fiscales.<br \/><strong>Ofrecemos:<\/strong><br \/>\u2714\ufe0f Estrategias para minimizar impuestos internacionales<br \/>\u2714\ufe0f Asesor\u00eda en tratados fiscales entre EE.UU. y otros pa\u00edses<br \/>\u2714\ufe0f Declaraciones de impuestos para no residentes y extranjeros inversionistas<br \/>\u2714\ufe0f Planificaci\u00f3n fiscal para empresas con operaciones en m\u00faltiples pa\u00edses.<br \/><strong>\u00bfQuieres emprender en EE.UU. con la mejor estrategia fiscal?<br \/><\/strong>Te guiamos para elegir la estructura empresarial ideal seg\u00fan tu negocio y optimizar tus impuestos.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21a4195 elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"21a4195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tCotiza sin compromiso\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-129c2a6 e-flex e-con-boxed e-con e-parent\" data-id=\"129c2a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62996cb e-con-full e-flex e-con e-child\" data-id=\"62996cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05dceb2 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"05dceb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICIO 7<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8148a5c elementor-widget elementor-widget-elementskit-heading\" data-id=\"8148a5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">TR\u00c1MITES MIGRATORIOS<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Brindamos asesor\u00eda integral y gesti\u00f3n experta en diversos procesos migratorios para ayudarte a regularizar tu situaci\u00f3n y alcanzar tus metas en los Estados Unidos. Nuestros servicios incluyen:<\/p>\n<p>\u2714\ufe0f <strong>Asilo:<\/strong> Asistencia en la solicitud de asilo para individuos que buscan protecci\u00f3n en EE. UU. debido a persecuci\u00f3n en su pa\u00eds de origen, ayud\u00e1ndote a completar la documentaci\u00f3n necesaria y a presentar tu caso de manera efectiva.<br \/>\u2714\ufe0f <strong>Estatus de Protecci\u00f3n Temporal (TPS):<\/strong> Orientaci\u00f3n en la aplicaci\u00f3n y renovaci\u00f3n del TPS, un estatus temporal otorgado a nacionales de pa\u00edses designados que enfrentan condiciones extraordinarias como conflictos armados o<br \/>desastres naturales.<br \/>\u2714\ufe0f <strong>Permiso de Trabajo (Formulario I-765):<\/strong> Ayuda en la obtenci\u00f3n de la Autorizaci\u00f3n de Empleo, permiti\u00e9ndote trabajar legalmente en EE. UU. mientras gestionas tu estatus migratorio.<br \/>\u2714\ufe0f Ajuste de Estatus (Green Card): Asesor\u00eda y apoyo en el proceso de conversi\u00f3n a residente permanente legal (Green Card), permiti\u00e9ndote obtener la residencia sin necesidad de salir de EE. UU.<\/p>\n<p><strong>\u00bfNecesitas ayuda con tu estatus migratorio?<\/strong><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c1236 elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"35c1236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ggintegralsolutions.com\/contacto\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tCotiza sin compromiso\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce117cd e-con-full e-flex e-con e-child\" data-id=\"ce117cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fcc65 elementor-widget elementor-widget-image\" data-id=\"f7fcc65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/tramites-1024x640.png\" class=\"attachment-large size-large wp-image-355\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/tramites-1024x640.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/tramites-300x188.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/tramites-768x480.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/tramites-18x12.png 18w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/03\/tramites.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc17d34 e-flex e-con-boxed e-con e-parent\" data-id=\"cc17d34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bf6a324 e-con-full e-flex e-con e-child\" data-id=\"bf6a324\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5d7fd elementor-widget elementor-widget-heading\" data-id=\"3f5d7fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Declaraci\u00f3n<br>de impuestos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36b1e47 elementor-widget elementor-widget-text-editor\" data-id=\"36b1e47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Te ayudamos a preparar y presentar tus impuestos:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-083202a e-grid e-con-full e-con e-child\" data-id=\"083202a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbaba8f elementor-widget__width-inherit ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"bbaba8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h4 class=\"elementskit-info-box-title\">\n                    Individuales                <\/h4>\n                        \t\t  \t<p>Maximiza tus reembolsos con nuestra asesor\u00eda.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8bf6f7 elementor-widget__width-inherit ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"a8bf6f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h4 class=\"elementskit-info-box-title\">\n                    Corporativos                <\/h4>\n                        \t\t  \t<p>Gestiona tus obligaciones fiscales y deducciones.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c00f51d elementor-widget__width-inherit ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"c00f51d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h4 class=\"elementskit-info-box-title\">\n                    Extranjeros                <\/h4>\n                        \t\t  \t<p>Declaraciones para no residentes y empresas.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-562edc4 e-con-full e-flex e-con e-child\" data-id=\"562edc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51b82e7 elementor-widget elementor-widget-image\" data-id=\"51b82e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1-1024x1024.png\" class=\"attachment-large size-large wp-image-302\" alt=\"\" srcset=\"https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1-1024x1024.png 1024w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1-300x300.png 300w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1-150x150.png 150w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1-768x768.png 768w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1-12x12.png 12w, https:\/\/ggintegralsolutions.com\/wp-content\/uploads\/2025\/02\/GG-1.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56f0644 e-flex e-con-boxed e-con e-parent\" data-id=\"56f0644\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-290fd2f elementor-widget elementor-widget-heading\" data-id=\"290fd2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conf\u00eda en nuestra experiencia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2b41ca e-flex e-con-boxed e-con e-parent\" data-id=\"b2b41ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-29ef18e e-con-full e-flex e-con e-child\" data-id=\"29ef18e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-342a79e elementor-widget__width-inherit ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"342a79e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h4 class=\"elementskit-info-box-title\">\n                    Asesor\u00eda 100% personalizada                <\/h4>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a9af90 e-con-full e-flex e-con e-child\" data-id=\"1a9af90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d1bef5 elementor-widget__width-inherit ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"0d1bef5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h4 class=\"elementskit-info-box-title\">\n                    Equipo registrado y certificado                <\/h4>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a4b2d5 e-con-full e-flex e-con e-child\" data-id=\"9a4b2d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebd405a elementor-widget__width-inherit ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"ebd405a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h4 class=\"elementskit-info-box-title\">\n                    Soluciones innovadoras                <\/h4>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27c0ed2 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"27c0ed2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56f8a48 e-con-full e-flex e-con e-child\" data-id=\"56f8a48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-274f2ca elementor-align-left elementor-widget elementor-widget-button\" data-id=\"274f2ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c654ab6 elementor-widget elementor-widget-elementskit-heading\" data-id=\"c654ab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Env\u00eda tus preguntas sobre nuestros servicios.<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Ya sea que necesites asesor\u00eda fiscal, declaraci\u00f3n de impuestos o servicios contables, nuestro equipo est\u00e1 listo para escucharte.<\/p>\n<p>\u00a0<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-08be7bd e-con-full e-flex e-con e-child\" data-id=\"08be7bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7095dd7 elementor-widget-mobile__width-initial elementor-widget__width-initial ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"7095dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-phone1\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    +1 (786) 8125 316                <\/h3>\n                        \t\t  \t<p>Phone<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af2ee8 elementor-widget-mobile__width-initial ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"3af2ee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-email\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    info@ggintegralsolutions.com                <\/h3>\n                        \t\t  \t<p>Email<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0509249 elementor-widget-mobile__width-initial ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"0509249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg aria-hidden=\"true\" class=\"elementkit-infobox-icon e-font-icon-svg e-fas-search-location\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M505.04 442.66l-99.71-99.69c-4.5-4.5-10.6-7-17-7h-16.3c27.6-35.3 44-79.69 44-127.99C416.03 93.09 322.92 0 208.02 0S0 93.09 0 207.98s93.11 207.98 208.02 207.98c48.3 0 92.71-16.4 128.01-44v16.3c0 6.4 2.5 12.5 7 17l99.71 99.69c9.4 9.4 24.6 9.4 33.9 0l28.3-28.3c9.4-9.4 9.4-24.59.1-33.99zm-297.02-90.7c-79.54 0-144-64.34-144-143.98 0-79.53 64.35-143.98 144-143.98 79.54 0 144 64.34 144 143.98 0 79.53-64.35 143.98-144 143.98zm.02-239.96c-40.78 0-73.84 33.05-73.84 73.83 0 32.96 48.26 93.05 66.75 114.86a9.24 9.24 0 0 0 14.18 0c18.49-21.81 66.75-81.89 66.75-114.86 0-40.78-33.06-73.83-73.84-73.83zm0 96c-13.26 0-24-10.75-24-24 0-13.26 10.75-24 24-24s24 10.74 24 24c0 13.25-10.75 24-24 24z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Florida, USA                <\/h3>\n                        \t\t  \t<p>Address<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41978ef e-con-full e-grid e-con e-child\" data-id=\"41978ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1b8dfe elementor-widget elementor-widget-shortcode\" data-id=\"b1b8dfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"mf-form-shortcode\">\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-157-157\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"157\"\r\n\t\t\tdata-action=\"https:\/\/ggintegralsolutions.com\/en\/wp-json\/metform\/v1\/entries\/insert\/157\"\r\n\t\t\tdata-wp-nonce=\"12e02714e1\"\r\n\t\t\tdata-form-nonce=\"8afbeb7ba8\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\tdata-payment-submit-before=\"0\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-157\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"157\" className=\"elementor elementor-157\" data-elementor-post-type=\"metform-form\">\n\t\t\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-26ea9738 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"26ea9738\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c8f3e4b\" data-id=\"7c8f3e4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-6a37e2f9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6a37e2f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24dd7809\" data-id=\"24dd7809\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-184663a1 elementor-widget elementor-widget-mf-text\" data-id=\"184663a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-first-name&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-184663a1\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Nombre`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-184663a1\"\r\n\t\t\t\tname=\"mf-first-name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`First name here`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-first-name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-first-name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e243baf\" data-id=\"1e243baf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-763108f5 elementor-widget elementor-widget-mf-text\" data-id=\"763108f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-last-name&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-763108f5\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Apellido`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-763108f5\"\r\n\t\t\t\tname=\"mf-last-name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Last name here`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-last-name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-last-name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-3a62ea78 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a62ea78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2c9a43de\" data-id=\"2c9a43de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-47e25ccc elementor-widget elementor-widget-mf-email\" data-id=\"47e25ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-email-47e25ccc\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Email`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\" \r\n\t\t\t\tid=\"mf-input-email-47e25ccc\" \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Add email`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-676e8797\" data-id=\"676e8797\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-20deb7b9 elementor-widget elementor-widget-mf-text\" data-id=\"20deb7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-subject&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-20deb7b9\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Asunto`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-20deb7b9\"\r\n\t\t\t\tname=\"mf-subject\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`How can we help you?`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-subject'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-subject\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-1f6daab4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1f6daab4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54f54cbc\" data-id=\"54f54cbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-7e5c045e elementor-widget elementor-widget-mf-textarea\" data-id=\"7e5c045e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-comment&quot;}\" data-widget_type=\"mf-textarea.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-area-7e5c045e\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Escribe tu mensaje`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<textarea className=\"mf-input mf-textarea mf-conditional-input\" id=\"mf-input-text-area-7e5c045e\"\r\n\t\t\t\tname=\"mf-comment\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Comments`) } \"\r\n\t\t\t\tcols=\"30\" rows=\"10\"\r\n\t\t\t\t\t\t\t\t\tonInput=${ parent.handleChange }\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-comment'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t><\/textarea>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-comment\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-4429ff08 elementor-widget elementor-widget-mf-recaptcha\" data-id=\"4429ff08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mf-recaptcha.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div id=\"recaptcha_site_key_v3\" data-sitekey=\"6LdJEFgsAAAAAFpI7fR6xjOyGWJJqdBuv20eCkiZ\"  className=\"recaptcha_site_key_v3 \">\n\t\t\t\t\t\t<input type=\"hidden\" className=\"g-recaptcha-response-v3\" name=\"g-recaptcha-response-v3\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-d3af341 elementor-widget__width-auto elementor-widget elementor-widget-mf-button\" data-id=\"d3af341\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mf-button.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper mf-conditional-input\" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Enviar`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SERVICIOS SERVICIO 1 IMPUESTOS PERSONALES Nos aseguramos de que declares tus impuestos de manera correcta, maximizandodeducciones y cr\u00e9ditos fiscales que pueden reducir tu carga tributaria. Te ayudamos con:\u2714\ufe0f Declaraci\u00f3n de impuestos individuales (Formulario 1040)\u2714\ufe0f Cr\u00e9ditos fiscales como el Earned Income Tax Credit (EITC) y el Child Tax Credit (CTC)\u2714\ufe0f Planificaci\u00f3n fiscal para aut\u00f3nomos y freelancers [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-174","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/pages\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":61,"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/pages\/174\/revisions"}],"predecessor-version":[{"id":410,"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/pages\/174\/revisions\/410"}],"wp:attachment":[{"href":"https:\/\/ggintegralsolutions.com\/en\/wp-json\/wp\/v2\/media?parent=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}